{"id":7606,"date":"2024-07-26T09:59:54","date_gmt":"2024-07-26T07:59:54","guid":{"rendered":"https:\/\/www.came.com\/global\/?page_id=7606"},"modified":"2024-07-26T10:11:54","modified_gmt":"2024-07-26T08:11:54","slug":"spk-landing","status":"publish","type":"page","link":"https:\/\/www.came.com\/global\/en\/spk-landing\/","title":{"rendered":"spk-landing"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\">\n<link rel=\"stylesheet\" type=\"text\/css\" href=\"..\/..\/sites\/default\/files\/spk-landing\/css\/normalize.css\" \/>\n<link rel=\"stylesheet\" type=\"text\/css\" href=\"..\/..\/sites\/default\/files\/spk-landing\/css\/fullpage.min.css\" \/>\n<link rel=\"stylesheet\" type=\"text\/css\" href=\"..\/..\/sites\/default\/files\/spk-landing\/css\/custom.css\" \/>\n\n<style>\n.section {\n    margin: 0;\n    padding: 0;\n  }\n  .main-header {\n      position: absolute;\n      width: 100vw;\n      background: transparent;\n      border: none;\n      z-index: 9;\n      transition: opacity 0.3s ease-in-out;\n  }\n  .main-header.hidden-header {\n      opacity: 0;\n      z-index: -1;\n  }\n  .main-header > .top {\n      display: none;\n  }\n  .main-header > .bottom {\n      margin: 0;\n      background: #fff;\n  }\n\nh1, h2, h3, h4, h5, h6 {\nfont-family: \"Came\",sans-serif;\nfont-weight: 400;\nline-height: 1;\n}\n\nh1 {font-size: 48px;}\nh2 {font-size: 37px;}\nh3 {font-size: 25px;}\n\n#fp-nav.fp-right {\nposition: absolute;\nbottom: 2.5vh;\n}\n\n#fp-nav ul {\nposition: absolute;\nbottom: 0;\n}\n\n#fp-nav ul li a span, .fp-slidesNav ul li a span {\nbackground: #009fe3;\nborder: 0.5px solid white;\n}\n\n#fp-nav.fp-right {\n  right: 30px;\n}\n\n#fp-nav ul li:last-of-type {display: none;}\n\n#section-footer-form {\ndisplay: flex;\nalign-items: center;\nheight: 100vh;\nbackground: #000;\n}\n\n#section-footer-form .-fixed-width .fp-tableCell {\n  height: 1080px;\ndisplay: flex;\nalign-items: center;\nwidth: 100vw;\n}\n\n.form-contacts {\nmax-width: 100vw;\nmargin: auto;\nwidth: 100vw\n}\n\n.form-contacts form {\nmargin: 0 auto;\nmax-width: 728px;\nwidth: 80%;\n}\n\n.form-contacts .form-title {\ncolor: #fff;\ntext-align: center;\ndisplay: block;\nfont-size: 15px;\n}\n\n.form-contacts .form-title span {\ncolor: #00B0ED;\n}\n\n.form-contacts .form-image {\nmargin: 0 auto;\nwidth: 100%;\nmax-width: 420px;\n}\n\n.form-contacts label {\ncolor: #fff;\n}\n\n.form-contacts p {\ncolor: #fff;\ndisplay: inline-block;\n}\n\n.form-contacts p.small-privacy {\nfont-size: 12px !important;\nline-height: 15px;\n}\n\n.form-contacts .title {\nmargin: 3vh 0 0 0;\n}\n\n.form-contacts .group {\nmargin-top: 2rem;\nmargin-bottom: 2rem;\n}\n\n.form-contacts input[type=\"submit\"] {\nmargin-top: 0.5rem;\n}\n\n.webform-confirmation-modal {\nwidth: 300px !important;\n}\n\ninput[type=\"radio\"] {\nmargin-right: 10px;\n}\n\n#edit-radio-dem-option label{\nmargin-right: 10px;\n}\n\n.smau-ribbon {\nposition: absolute; top: 100px; right: 20px; width: 160px;\n}\n\n@media only screen and (orientation: portrait) and (max-width: 991px){\n.form-contacts .group {\n  margin-top: 1rem;\n  margin-bottom: 1rem;\n}\n.form-contacts input[type=\"text\"], .form-contacts input[type=\"email\"] {\n  padding: 0.4rem 1rem;\n  margin: 0.4rem 0;\n}\n.form-contacts .item {\n  margin-bottom: 1rem;\n}\nh1 {\n  font-size: 35px;\n}\nh2 {\n  font-size: 28px;\n}\nh3 {\n  font-size: 20px;\n}\n#section-03 .slide#slide-06 .container .box-06-titolo .box-06-titolo-txt, #section-06 .slide#slide-07 .container .box-07-titolo .box-07-titolo-txt, #section-07 .slide#slide-08 .container .box-08-titolo .box-08-titolo-txt {\n  height: auto;\n}\n.smau-ribbon {\n  top: 60px; right: 0; width: 128px;\n}\n}\n\n@media only screen and (orientation: landscape) and (max-width: 991px){\n.smau-ribbon {\n  top: 60px; right: auto; left: 20px; width: 128px;\n}\n}\n\n@media only screen and (orientation: landscape) and (max-width: 1024px) and (max-height: 768px){\n.smau-ribbon {\n  top: 90px; width: 128px; right: 10px;\n}\n}\n\n@media only screen and (orientation: landscape) and (min-width: 992px){\n#fp-nav.fp-left {\n  left: 17px;\n}\n#section-footer-double .slide#slide-footer-double .box-footer-double-bg-dx {\n  background-position: center center;\n}\n}\n\n@media only screen and (min-width: 1601px){\n.smau-ribbon {\n  width: 192px;\n}\n}\n\n#landscape-alert {\ndisplay: none !important;\n}\n<\/style>\n\n<div id=\"fullpage\">\n\n<!--SECTION INTRO-->\n<div class=\"section\" id=\"section-intro\">\n    <!--slide intro-->\n    <div class=\"slide\" id=\"slide-intro\">\n        <div class=\"box-intro-top\">\n            <div class=\"video-fs\">\n                <video muted autoplay data-keepplaying playsinline preload=\"auto\" id=\"01_head_landingsite_spk\">\n                    <source data-src=\"..\/..\/sites\/default\/files\/spk-landing\/video\/01_head_landingsite_spk.mp4\" type=\"video\/mp4\" \/>\n                <\/video>\n            <\/div>\n        <\/div>\n        <div class=\"container\">\n            <div class=\"box-intro-titolo\">\n                <div class=\"box-intro-titolo-txt\">\n                    <h1><span>ZERO KM<\/span> SERVICE<\/h1>\n                    <h2>A BREAKTHROUGH<br>\n                    IN PARKING SERVICE<\/h2>\n                    <p><span class=\"btn btn-ev\" id=\"next-slide-video\">WATCH THE VIDEO&nbsp;&gt;<\/span><\/p>\n                    <p><span class=\"no-btn\" id=\"next-section-01\">CONTACT US FOR MORE INFO&nbsp;&gt;<\/span><\/p>\n                    <p><img decoding=\"async\" src=\"..\/..\/sites\/default\/files\/spk-landing\/img\/logo-parkare.png\" alt=\"Came Parkare\"><\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <img decoding=\"async\" src=\"..\/..\/sites\/default\/files\/spk-landing\/img\/smau-ribbon.png\" alt=\"SMAU Ribbon\" class=\"smau-ribbon\">\n        <span class=\"scroll-down\"><strong>SCROLL DOWN<\/strong> TO DISCOVER MORE<\/span>\n    <\/div>\n    <!--slide video-->\n    <div class=\"slide\" id=\"slide-video\">\n        <span id=\"box-video-close\" class=\"btn btn-inv\">X<\/span>\n        <div class=\"container\">\n            <div class=\"video-16-9\">\n                <video controls id=\"video-16-9\">\n                    <source data-src=\"..\/..\/sites\/default\/files\/spk-landing\/video\/came_spk_en.mp4\" type=\"video\/mp4\" \/>\n                <\/video>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION 01-->\n<div class=\"section\" id=\"section-01\">\n    <!--slide 01-->\n    <div class=\"slide\" id=\"slide-01\">\n        <div class=\"box-01-img\"><\/div>\n        <div class=\"container\">\n            <div class=\"box-01-titolo\">\n                <div class=\"box-01-titolo-txt\">\n                    <h3><span>A CUTTING EDGE CONCEPT<\/span><br>\n                    TO CHANGE PARKING SERVICE<br>\n                    <span>FOREVER<\/span><\/h3>\n                    <ul>\n                        <li>no need to call the Service provider<\/li>\n                        <li>no more waiting for a specialised technician<\/li>\n                        <li>no stress for the car park manager<\/li>\n                    <\/ul>\n                    <p>Discover our innovative vision with Renato Berto, Vice President CAME Parking Division \/ CEO CAME PARKARE<\/p>\n                    <p><a class=\"btn btn-ev\" href=\"..\/..\/sites\/default\/files\/spk-landing\/pdf\/ZeroKmService_Article_RBerto_EN.pdf\" target=\"_blank\" rel=\"noopener\">READ THE ARTICLE&nbsp;&gt;<\/a><\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION 02-->\n<div class=\"section\" id=\"section-02\">\n    <!--slide 02-->\n    <div class=\"slide\" id=\"slide-02\">\n        <div class=\"container\">\n            <div class=\"box-02-titolo\">\n                <div class=\"box-02-titolo-txt\">\n                    <h3><span>SOFTWARE<\/span> IS BECOMING<br>\n                    INCREASINGLY MORE IMPORTANT<br>\n                    THAN <span>HARDWARE.<\/span><br>\n                    <span>SERVICE<\/span> CAN PLAY<br>\n                    A KEY ROLE.<\/h3>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"box-02-video\">\n            <div class=\"video-fs\">\n                <video muted autoplay loop data-keepplaying playsinline preload=\"auto\" id=\"03_hdServiceSw_landingsite_spk\">\n                    <source data-src=\"..\/..\/sites\/default\/files\/spk-landing\/video\/03_hdServiceSw_landingsite_spk.mp4\" type=\"video\/mp4\" \/>\n                <\/video>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION 03-->\n<div class=\"section\" id=\"section-03\">\n    <!--slide 06-->\n    <div class=\"slide\" id=\"slide-06\">\n        <div class=\"box-06-img\"><\/div>\n        <div class=\"container\">\n            <div class=\"box-06-titolo\">\n                <div class=\"box-06-buttons\">\n                    <span id=\"btn-2-1\" class=\"sel\">1<\/span>\n                    <span id=\"btn-2-2\">2<\/span>\n                    <span id=\"btn-2-3\">3<\/span>\n                <\/div>\n                <div class=\"box-06-titolo-txt\">\n                    <h3><span class=\"hide-340\">THE <\/span>REVOLUTION IN SERVICE MODEL<br>\n                    <span class=\"hide-340\">IS <\/span>BASED ON 3 PILLARS<br>\n                    <span class=\"color\">NEW HARDWARE DESIGN<br>\n                    REPAIR FAILURES<br>\n                    QUICKLY AND AUTONOMOUSLY<\/span><\/h3>\n                    <p>Devices are produced in robust and modular kits. A huge advantage! Any parking employee can swap them quickly and autonomously. Specialised technicians are no longer required.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION 06-->\n<div class=\"section\" id=\"section-06\">\n    <!--slide 07-->\n    <div class=\"slide\" id=\"slide-07\">\n        <div class=\"box-07-img\"><\/div>\n        <div class=\"container\">\n            <div class=\"box-07-titolo\">\n                <div class=\"box-07-buttons\">\n                    <span id=\"btn-3-1\">1<\/span>\n                    <span id=\"btn-3-2\" class=\"sel\">2<\/span>\n                    <span id=\"btn-3-3\">3<\/span>\n                <\/div>\n                <div class=\"box-07-titolo-txt\">\n                    <h3><span class=\"hide-340\">THE <\/span>REVOLUTION IN SERVICE MODEL<br>\n                    <span class=\"hide-340\">IS <\/span>BASED ON 3 PILLARS<br>\n                    <span class=\"color\">NEW SMART SOFTWARE<br>\n                    TO INFORM AND GUIDE STAFF TO BE<br>\n                    SELF-SUFFICIENT IN REAL TIME<\/span><\/h3>\n                    <p>Software capable of sending real-time data to inform and guide the operator&#8217;s staff to be self-sufficient in both preventive and corrective tasks.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION 07-->\n<div class=\"section\" id=\"section-07\">\n    <!--slide 08-->\n    <div class=\"slide\" id=\"slide-08\">\n        <div class=\"box-08-video\">\n            <div class=\"video-fs\">\n                <video muted autoplay loop data-keepplaying playsinline preload=\"auto\" id=\"04_03pillar_landingsite_spk\">\n                    <source data-src=\"..\/..\/sites\/default\/files\/spk-landing\/video\/04_03pillar_landingsite_spk.mp4\" type=\"video\/mp4\" \/>\n                <\/video>\n            <\/div>\n        <\/div>\n        <div class=\"container\">\n            <div class=\"box-08-titolo\">\n                <div class=\"box-08-buttons\">\n                    <span id=\"btn-4-1\">1<\/span>\n                    <span id=\"btn-4-2\">2<\/span>\n                    <span id=\"btn-4-3\" class=\"sel\">3<\/span>\n                <\/div>\n                <div class=\"box-08-titolo-txt\">\n                    <h3><span class=\"hide-340\">THE <\/span>REVOLUTION IN SERVICE MODEL<br>\n                    <span class=\"hide-340\">IS <\/span>BASED ON 3 PILLARS<br>\n                    <span class=\"color\">THE SMARTEST TECHNOLOGY<br>\n                    MODULAR KIT UNITS<br>\n                    FOOL-PROOF SYSTEM<br>\n                    TPM METHODOLOGY<\/span><\/h3>\n                    <p>A modular and intuitive structure, supported by Artificial Intelligence algorithms, ensuring never-before-seen operational continuity.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION 04-->\n<div class=\"section\" id=\"section-04\">\n    <!--slide 04-->\n    <div class=\"slide\" id=\"slide-04\">\n        <div class=\"container\">\n            <div class=\"box-04-titolo\">\n                <div class=\"box-04-titolo-txt\">\n                    <h3>A NEW <span>VISION<\/span><br>\n                    WITH NEW <span>GOALS.<\/span><\/h3>\n                    <p>Zero KM Service ensures a never-before-seen operational continuity, an improved customer experience and a huge impact on the EBITDA of operators in the sector.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"box-04-video\">\n            <div class=\"video-fs\">\n                <video muted autoplay data-keepplaying playsinline preload=\"auto\" id=\"05_ebitda_landingsite_spk\">\n                    <source data-src=\"..\/..\/sites\/default\/files\/spk-landing\/video\/05_ebitda_landingsite_spk.mp4\" type=\"video\/mp4\" \/>\n                <\/video>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION 05-->\n<div class=\"section\" id=\"section-05\">\n    <!--slide 09-->\n    <div class=\"slide\" id=\"slide-09\">\n        <div class=\"box-09-img box-09-img-en\"><\/div>\n        <div class=\"container\">\n            <div class=\"box-09-titolo\">\n                <div class=\"box-09-titolo-txt\">\n                    <h3><span>SPK, PARKING MANAGEMENT SYSTEM.<\/span><br>\n                    THE NEW FRONTIER IN <span>ZERO KM<\/span> SERVICE.<\/h3>\n                    <p><span class=\"btn btn-ev\" id=\"next-section-02\">DOWNLOAD THE BROCHURE&nbsp;&gt;<\/span><\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!--SECTION FOOTER FORM-->\n<div class=\"section\" id=\"section-footer-form\">\n   \n<\/div>\n\n<\/div>\n\n<div id=\"landscape-alert\" style=\"display:none;\"><\/div>\n\n<script type=\"text\/javascript\" src=\"..\/..\/sites\/default\/files\/spk-landing\/js\/scrolloverflow.min.js\" defer><\/script>\n<script type=\"text\/javascript\" src=\"..\/..\/sites\/default\/files\/spk-landing\/js\/fullpage.min.js\" defer><\/script>\n<script type=\"text\/javascript\" src=\"..\/..\/sites\/default\/files\/spk-landing\/js\/custom.js\" defer><\/script>\n<\/div>\n\n\n\n<div class=\"forminator-guttenberg\"><div class=\"forminator-ui forminator-custom-form forminator-custom-form-6039 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-6039\" data-uid=\"6a57ec0f61893\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-6039\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-6039 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"6039\"\n\t\t\t\t\n\t\t\t\tdata-design=\"default\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\tdata-grid=\"open\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\tstyle=\"display: none;\"\n\t\t\t\t\n\t\t\t\tdata-uid=\"6a57ec0f61893\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"html-1\" class=\"forminator-field-html forminator-col forminator-col-12 \"><div class=\"forminator-field forminator-merge-tags\" data-field=\"html-1\"><h2 class=\"form-title\"><span>I am interested in<\/span><br>\nzero KM <span>Service<\/span> Project<\/h2><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"checkbox-1\" class=\"forminator-field-checkbox forminator-col forminator-col-12 \"><div role=\"group\" class=\"forminator-field\" aria-labelledby=\"forminator-checkbox-group-6a57ec0f61893-label\"><label id=\"forminator-field-checkbox-1-1-6a57ec0f61893-label\" for=\"forminator-field-checkbox-1-1-6a57ec0f61893\" class=\"forminator-checkbox\" title=\"Download the Zero KM Service brochure\"><input type=\"checkbox\" name=\"checkbox-1[]\" value=\"one\" id=\"forminator-field-checkbox-1-1-6a57ec0f61893\" aria-labelledby=\"forminator-field-checkbox-1-1-6a57ec0f61893-label\" data-calculation=\"0\"   data-hidden-behavior=\"zero\" aria-describedby=\"forminator-field-checkbox-1-6a57ec0f61893-description\"\/><span class=\"forminator-checkbox-box\" aria-hidden=\"true\"><\/span><span class=\"forminator-checkbox-label\">Download the Zero KM Service brochure<\/span><\/label><label id=\"forminator-field-checkbox-1-2-6a57ec0f61893-label\" for=\"forminator-field-checkbox-1-2-6a57ec0f61893\" class=\"forminator-checkbox\" title=\"Please contact me for further details\"><input type=\"checkbox\" name=\"checkbox-1[]\" value=\"two\" id=\"forminator-field-checkbox-1-2-6a57ec0f61893\" aria-labelledby=\"forminator-field-checkbox-1-2-6a57ec0f61893-label\" data-calculation=\"0\"   data-hidden-behavior=\"zero\" aria-describedby=\"forminator-field-checkbox-1-6a57ec0f61893-description\"\/><span class=\"forminator-checkbox-box\" aria-hidden=\"true\"><\/span><span class=\"forminator-checkbox-label\">Please contact me for further details<\/span><\/label><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-6 \"><div class=\"forminator-field\"><label for=\"forminator-field-name-1_6a57ec0f61893\" id=\"forminator-field-name-1_6a57ec0f61893-label\" class=\"forminator-label\">name surname <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1\" value=\"\" placeholder=\"\" id=\"forminator-field-name-1_6a57ec0f61893\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" \/><\/div><\/div><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-6 \"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a57ec0f61893\" id=\"forminator-field-email-1_6a57ec0f61893-label\" class=\"forminator-label\">Email <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"\" id=\"forminator-field-email-1_6a57ec0f61893\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-1\" class=\"forminator-field-address forminator-col forminator-col-6 \"><div class=\"forminator-row\" data-multiple=\"false\"><div id=\"address-1-country\" class=\"forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-6039__field--address-1-country_6a57ec0f61893\" id=\"forminator-field-6039__field--address-1-country_6a57ec0f61893-label\" class=\"forminator-label\">Country <span class=\"forminator-required\">*<\/span><\/label><select name=\"address-1-country\" id=\"forminator-field-6039__field--address-1-country_6a57ec0f61893\" class=\"forminator-select2\" data-search=\"true\" data-placeholder=\"Select country\" data-default-value=\"\"><option value=\"\" data-country-code=\"\" selected=\"selected\"><\/option><option value=\"Afghanistan\" data-country-code=\"AF\" >Afghanistan<\/option><option value=\"Albania\" data-country-code=\"AL\" >Albania<\/option><option value=\"Algeria\" data-country-code=\"DZ\" >Algeria<\/option><option value=\"American Samoa\" data-country-code=\"AS\" >American Samoa<\/option><option value=\"Andorra\" data-country-code=\"AD\" >Andorra<\/option><option value=\"Angola\" data-country-code=\"AO\" >Angola<\/option><option value=\"Anguilla\" data-country-code=\"AI\" >Anguilla<\/option><option value=\"Antarctica\" data-country-code=\"AQ\" >Antarctica<\/option><option value=\"Antigua and Barbuda\" data-country-code=\"AG\" >Antigua and Barbuda<\/option><option value=\"Argentina\" data-country-code=\"AR\" >Argentina<\/option><option value=\"Armenia\" data-country-code=\"AM\" >Armenia<\/option><option value=\"Australia\" data-country-code=\"AU\" >Australia<\/option><option value=\"Aruba\" data-country-code=\"AW\" >Aruba<\/option><option value=\"Austria\" data-country-code=\"AT\" >Austria<\/option><option value=\"Azerbaijan\" data-country-code=\"AZ\" >Azerbaijan<\/option><option value=\"Bahamas\" data-country-code=\"BS\" >Bahamas<\/option><option value=\"Bahrain\" data-country-code=\"BH\" >Bahrain<\/option><option value=\"Bangladesh\" data-country-code=\"BD\" >Bangladesh<\/option><option value=\"Barbados\" data-country-code=\"BB\" >Barbados<\/option><option value=\"Belarus\" data-country-code=\"BY\" >Belarus<\/option><option value=\"Belgium\" data-country-code=\"BE\" >Belgium<\/option><option value=\"Belize\" data-country-code=\"BZ\" >Belize<\/option><option value=\"Benin\" data-country-code=\"BJ\" >Benin<\/option><option value=\"Bermuda\" data-country-code=\"BM\" >Bermuda<\/option><option value=\"Bhutan\" data-country-code=\"BT\" >Bhutan<\/option><option value=\"Bolivia\" data-country-code=\"BO\" >Bolivia<\/option><option value=\"Bosnia and Herzegovina\" data-country-code=\"BA\" >Bosnia and Herzegovina<\/option><option value=\"Botswana\" data-country-code=\"BW\" >Botswana<\/option><option value=\"Bouvet Island\" data-country-code=\"BV\" >Bouvet Island<\/option><option value=\"Brazil\" data-country-code=\"BR\" >Brazil<\/option><option value=\"British Indian Ocean Territory\" data-country-code=\"IO\" >British Indian Ocean Territory<\/option><option value=\"Brunei\" data-country-code=\"BN\" >Brunei<\/option><option value=\"Bulgaria\" data-country-code=\"BG\" >Bulgaria<\/option><option value=\"Burkina Faso\" data-country-code=\"BF\" >Burkina Faso<\/option><option value=\"Burundi\" data-country-code=\"BI\" >Burundi<\/option><option value=\"Cambodia\" data-country-code=\"KH\" >Cambodia<\/option><option value=\"Cameroon\" data-country-code=\"CM\" >Cameroon<\/option><option value=\"Canada\" data-country-code=\"CA\" >Canada<\/option><option value=\"Cabo Verde\" data-country-code=\"CV\" >Cabo Verde<\/option><option value=\"Cayman Islands\" data-country-code=\"KY\" >Cayman Islands<\/option><option value=\"Central African Republic\" data-country-code=\"CF\" >Central African Republic<\/option><option value=\"Chad\" data-country-code=\"TD\" >Chad<\/option><option value=\"Chile\" data-country-code=\"CL\" >Chile<\/option><option value=\"China, People's Republic of\" data-country-code=\"CN\" >China, People's Republic of<\/option><option value=\"Christmas Island\" data-country-code=\"CX\" >Christmas Island<\/option><option value=\"Cocos Islands\" data-country-code=\"CC\" >Cocos Islands<\/option><option value=\"Colombia\" data-country-code=\"CO\" >Colombia<\/option><option value=\"Comoros\" data-country-code=\"KM\" >Comoros<\/option><option value=\"Congo, Democratic Republic of the\" data-country-code=\"CD\" >Congo, Democratic Republic of the<\/option><option value=\"Congo, Republic of the\" data-country-code=\"CG\" >Congo, Republic of the<\/option><option value=\"Cook Islands\" data-country-code=\"CK\" >Cook Islands<\/option><option value=\"Costa Rica\" data-country-code=\"CR\" >Costa Rica<\/option><option value=\"C\u00f4te d'Ivoire\" data-country-code=\"CI\" >C\u00f4te d'Ivoire<\/option><option value=\"Croatia\" data-country-code=\"HR\" >Croatia<\/option><option value=\"Cuba\" data-country-code=\"CU\" >Cuba<\/option><option value=\"Cura\u00e7ao\" data-country-code=\"CW\" >Cura\u00e7ao<\/option><option value=\"Cyprus\" data-country-code=\"CY\" >Cyprus<\/option><option value=\"Czech Republic\" data-country-code=\"CZ\" >Czech Republic<\/option><option value=\"Denmark\" data-country-code=\"DK\" >Denmark<\/option><option value=\"Djibouti\" data-country-code=\"DJ\" >Djibouti<\/option><option value=\"Dominica\" data-country-code=\"DM\" >Dominica<\/option><option value=\"Dominican Republic\" data-country-code=\"DO\" >Dominican Republic<\/option><option value=\"East Timor\" data-country-code=\"TL\" >East Timor<\/option><option value=\"Ecuador\" data-country-code=\"EC\" >Ecuador<\/option><option value=\"Egypt\" data-country-code=\"EG\" >Egypt<\/option><option value=\"El Salvador\" data-country-code=\"SV\" >El Salvador<\/option><option value=\"Equatorial Guinea\" data-country-code=\"GQ\" >Equatorial Guinea<\/option><option value=\"Eritrea\" data-country-code=\"ER\" >Eritrea<\/option><option value=\"Estonia\" data-country-code=\"EE\" >Estonia<\/option><option value=\"Ethiopia\" data-country-code=\"ET\" >Ethiopia<\/option><option value=\"Falkland Islands\" data-country-code=\"FK\" >Falkland Islands<\/option><option value=\"Faroe Islands\" data-country-code=\"FO\" >Faroe Islands<\/option><option value=\"Fiji\" data-country-code=\"FJ\" >Fiji<\/option><option value=\"Finland\" data-country-code=\"FI\" >Finland<\/option><option value=\"France\" data-country-code=\"FR\" >France<\/option><option value=\"France, Metropolitan\" data-country-code=\"FX\" >France, Metropolitan<\/option><option value=\"French Guiana\" data-country-code=\"GF\" >French Guiana<\/option><option value=\"French Polynesia\" data-country-code=\"PF\" >French Polynesia<\/option><option value=\"French South Territories\" data-country-code=\"TF\" >French South Territories<\/option><option value=\"Gabon\" data-country-code=\"GA\" >Gabon<\/option><option value=\"Gambia\" data-country-code=\"GM\" >Gambia<\/option><option value=\"Georgia\" data-country-code=\"GE\" >Georgia<\/option><option value=\"Germany\" data-country-code=\"DE\" >Germany<\/option><option value=\"Guernsey\" data-country-code=\"GG\" >Guernsey<\/option><option value=\"Ghana\" data-country-code=\"GH\" >Ghana<\/option><option value=\"Gibraltar\" data-country-code=\"GI\" >Gibraltar<\/option><option value=\"Greece\" data-country-code=\"GR\" >Greece<\/option><option value=\"Greenland\" data-country-code=\"GL\" >Greenland<\/option><option value=\"Grenada\" data-country-code=\"GD\" >Grenada<\/option><option value=\"Guadeloupe\" data-country-code=\"GP\" >Guadeloupe<\/option><option value=\"Guam\" data-country-code=\"GU\" >Guam<\/option><option value=\"Guatemala\" data-country-code=\"GT\" >Guatemala<\/option><option value=\"Guinea\" data-country-code=\"GN\" >Guinea<\/option><option value=\"Guinea-Bissau\" data-country-code=\"GW\" >Guinea-Bissau<\/option><option value=\"Guyana\" data-country-code=\"GY\" >Guyana<\/option><option value=\"Haiti\" data-country-code=\"HT\" >Haiti<\/option><option value=\"Heard Island And Mcdonald Island\" data-country-code=\"HM\" >Heard Island And Mcdonald Island<\/option><option value=\"Honduras\" data-country-code=\"HN\" >Honduras<\/option><option value=\"Hong Kong\" data-country-code=\"HK\" >Hong Kong<\/option><option value=\"Hungary\" data-country-code=\"HU\" >Hungary<\/option><option value=\"Iceland\" data-country-code=\"IS\" >Iceland<\/option><option value=\"India\" data-country-code=\"IN\" >India<\/option><option value=\"Indonesia\" data-country-code=\"ID\" >Indonesia<\/option><option value=\"Iran\" data-country-code=\"IR\" >Iran<\/option><option value=\"Iraq\" data-country-code=\"IQ\" >Iraq<\/option><option value=\"Ireland\" data-country-code=\"IE\" >Ireland<\/option><option value=\"Israel\" data-country-code=\"IL\" >Israel<\/option><option value=\"Italy\" data-country-code=\"IT\" >Italy<\/option><option value=\"Jamaica\" data-country-code=\"JM\" >Jamaica<\/option><option value=\"Japan\" data-country-code=\"JP\" >Japan<\/option><option value=\"Jersey\" data-country-code=\"JE\" >Jersey<\/option><option value=\"Johnston Island\" data-country-code=\"JT\" >Johnston Island<\/option><option value=\"Jordan\" data-country-code=\"JO\" >Jordan<\/option><option value=\"Kazakhstan\" data-country-code=\"KZ\" >Kazakhstan<\/option><option value=\"Kenya\" data-country-code=\"KE\" >Kenya<\/option><option value=\"Kiribati\" data-country-code=\"KI\" >Kiribati<\/option><option value=\"Korea, Democratic People's Republic of\" data-country-code=\"KP\" >Korea, Democratic People's Republic of<\/option><option value=\"Korea, Republic of\" data-country-code=\"KR\" >Korea, Republic of<\/option><option value=\"Kosovo\" data-country-code=\"XK\" >Kosovo<\/option><option value=\"Kuwait\" data-country-code=\"KW\" >Kuwait<\/option><option value=\"Kyrgyzstan\" data-country-code=\"KG\" >Kyrgyzstan<\/option><option value=\"Lao People's Democratic Republic\" data-country-code=\"LA\" >Lao People's Democratic Republic<\/option><option value=\"Latvia\" data-country-code=\"LV\" >Latvia<\/option><option value=\"Lebanon\" data-country-code=\"LB\" >Lebanon<\/option><option value=\"Lesotho\" data-country-code=\"LS\" >Lesotho<\/option><option value=\"Liberia\" data-country-code=\"LR\" >Liberia<\/option><option value=\"Libya\" data-country-code=\"LY\" >Libya<\/option><option value=\"Liechtenstein\" data-country-code=\"LI\" >Liechtenstein<\/option><option value=\"Lithuania\" data-country-code=\"LT\" >Lithuania<\/option><option value=\"Luxembourg\" data-country-code=\"LU\" >Luxembourg<\/option><option value=\"Macau\" data-country-code=\"MO\" >Macau<\/option><option value=\"North Macedonia\" data-country-code=\"MK\" >North Macedonia<\/option><option value=\"Madagascar\" data-country-code=\"MG\" >Madagascar<\/option><option value=\"Malawi\" data-country-code=\"MW\" >Malawi<\/option><option value=\"Malaysia\" data-country-code=\"MY\" >Malaysia<\/option><option value=\"Maldives\" data-country-code=\"MV\" >Maldives<\/option><option value=\"Mali\" data-country-code=\"ML\" >Mali<\/option><option value=\"Malta\" data-country-code=\"MT\" >Malta<\/option><option value=\"Marshall Islands\" data-country-code=\"MH\" >Marshall Islands<\/option><option value=\"Martinique\" data-country-code=\"MQ\" >Martinique<\/option><option value=\"Mauritania\" data-country-code=\"MR\" >Mauritania<\/option><option value=\"Mauritius\" data-country-code=\"MU\" >Mauritius<\/option><option value=\"Mayotte\" data-country-code=\"YT\" >Mayotte<\/option><option value=\"Mexico\" data-country-code=\"MX\" >Mexico<\/option><option value=\"Micronesia\" data-country-code=\"FM\" >Micronesia<\/option><option value=\"Moldova\" data-country-code=\"MD\" >Moldova<\/option><option value=\"Monaco\" data-country-code=\"MC\" >Monaco<\/option><option value=\"Mongolia\" data-country-code=\"MN\" >Mongolia<\/option><option value=\"Montserrat\" data-country-code=\"MS\" >Montserrat<\/option><option value=\"Montenegro\" data-country-code=\"ME\" >Montenegro<\/option><option value=\"Morocco\" data-country-code=\"MA\" >Morocco<\/option><option value=\"Mozambique\" data-country-code=\"MZ\" >Mozambique<\/option><option value=\"Myanmar\" data-country-code=\"MM\" >Myanmar<\/option><option value=\"Namibia\" data-country-code=\"NA\" >Namibia<\/option><option value=\"Nauru\" data-country-code=\"NR\" >Nauru<\/option><option value=\"Nepal\" data-country-code=\"NP\" >Nepal<\/option><option value=\"Netherlands\" data-country-code=\"NL\" >Netherlands<\/option><option value=\"Netherlands Antilles\" data-country-code=\"AN\" >Netherlands Antilles<\/option><option value=\"New Caledonia\" data-country-code=\"NC\" >New Caledonia<\/option><option value=\"New Zealand\" data-country-code=\"NZ\" >New Zealand<\/option><option value=\"Nicaragua\" data-country-code=\"NI\" >Nicaragua<\/option><option value=\"Niger\" data-country-code=\"NE\" >Niger<\/option><option value=\"Nigeria\" data-country-code=\"NG\" >Nigeria<\/option><option value=\"Niue\" data-country-code=\"NU\" >Niue<\/option><option value=\"Norfolk Island\" data-country-code=\"NF\" >Norfolk Island<\/option><option value=\"Northern Mariana Islands\" data-country-code=\"MP\" >Northern Mariana Islands<\/option><option value=\"Norway\" data-country-code=\"NO\" >Norway<\/option><option value=\"Oman\" data-country-code=\"OM\" >Oman<\/option><option value=\"Pakistan\" data-country-code=\"PK\" >Pakistan<\/option><option value=\"Palau\" data-country-code=\"PW\" >Palau<\/option><option value=\"Palestine, State of\" data-country-code=\"PS\" >Palestine, State of<\/option><option value=\"Panama\" data-country-code=\"PA\" >Panama<\/option><option value=\"Papua New Guinea\" data-country-code=\"PG\" >Papua New Guinea<\/option><option value=\"Paraguay\" data-country-code=\"PY\" >Paraguay<\/option><option value=\"Peru\" data-country-code=\"PE\" >Peru<\/option><option value=\"Philippines\" data-country-code=\"PH\" >Philippines<\/option><option value=\"Pitcairn Islands\" data-country-code=\"PN\" >Pitcairn Islands<\/option><option value=\"Poland\" data-country-code=\"PL\" >Poland<\/option><option value=\"Portugal\" data-country-code=\"PT\" >Portugal<\/option><option value=\"Puerto Rico\" data-country-code=\"PR\" >Puerto Rico<\/option><option value=\"Qatar\" data-country-code=\"QA\" >Qatar<\/option><option value=\"Reunion Island\" data-country-code=\"RE\" >Reunion Island<\/option><option value=\"Romania\" data-country-code=\"RO\" >Romania<\/option><option value=\"Russia\" data-country-code=\"RU\" >Russia<\/option><option value=\"Rwanda\" data-country-code=\"RW\" >Rwanda<\/option><option value=\"Saint Kitts and Nevis\" data-country-code=\"KN\" >Saint Kitts and Nevis<\/option><option value=\"Saint Lucia\" data-country-code=\"LC\" >Saint Lucia<\/option><option value=\"Saint Vincent and the Grenadines\" data-country-code=\"VC\" >Saint Vincent and the Grenadines<\/option><option value=\"Samoa\" data-country-code=\"WS\" >Samoa<\/option><option value=\"Saint Helena\" data-country-code=\"SH\" >Saint Helena<\/option><option value=\"Saint Pierre & Miquelon\" data-country-code=\"PM\" >Saint Pierre & Miquelon<\/option><option value=\"San Marino\" data-country-code=\"SM\" >San Marino<\/option><option value=\"Sao Tome and Principe\" data-country-code=\"ST\" >Sao Tome and Principe<\/option><option value=\"Saudi Arabia\" data-country-code=\"SA\" >Saudi Arabia<\/option><option value=\"Senegal\" data-country-code=\"SN\" >Senegal<\/option><option value=\"Serbia\" data-country-code=\"RS\" >Serbia<\/option><option value=\"Seychelles\" data-country-code=\"SC\" >Seychelles<\/option><option value=\"Sierra Leone\" data-country-code=\"SL\" >Sierra Leone<\/option><option value=\"Singapore\" data-country-code=\"SG\" >Singapore<\/option><option value=\"Sint Maarten\" data-country-code=\"MF\" >Sint Maarten<\/option><option value=\"Slovakia\" data-country-code=\"SK\" >Slovakia<\/option><option value=\"Slovenia\" data-country-code=\"SI\" >Slovenia<\/option><option value=\"Solomon Islands\" data-country-code=\"SB\" >Solomon Islands<\/option><option value=\"Somalia\" data-country-code=\"SO\" >Somalia<\/option><option value=\"South Africa\" data-country-code=\"ZA\" >South Africa<\/option><option value=\"South Georgia and South Sandwich\" data-country-code=\"GS\" >South Georgia and South Sandwich<\/option><option value=\"Spain\" data-country-code=\"ES\" >Spain<\/option><option value=\"Sri Lanka\" data-country-code=\"LK\" >Sri Lanka<\/option><option value=\"Stateless Persons\" data-country-code=\"XX\" >Stateless Persons<\/option><option value=\"Sudan\" data-country-code=\"SD\" >Sudan<\/option><option value=\"Sudan, South\" data-country-code=\"SS\" >Sudan, South<\/option><option value=\"Suriname\" data-country-code=\"SR\" >Suriname<\/option><option value=\"Svalbard and Jan Mayen\" data-country-code=\"SJ\" >Svalbard and Jan Mayen<\/option><option value=\"Swaziland\" data-country-code=\"SZ\" >Swaziland<\/option><option value=\"Sweden\" data-country-code=\"SE\" >Sweden<\/option><option value=\"Switzerland\" data-country-code=\"CH\" >Switzerland<\/option><option value=\"Syria\" data-country-code=\"SY\" >Syria<\/option><option value=\"Taiwan, Republic of China\" data-country-code=\"TW\" >Taiwan, Republic of China<\/option><option value=\"Tajikistan\" data-country-code=\"TJ\" >Tajikistan<\/option><option value=\"Tanzania\" data-country-code=\"TZ\" >Tanzania<\/option><option value=\"Thailand\" data-country-code=\"TH\" >Thailand<\/option><option value=\"Togo\" data-country-code=\"TG\" >Togo<\/option><option value=\"Tokelau\" data-country-code=\"TK\" >Tokelau<\/option><option value=\"Tonga\" data-country-code=\"TO\" >Tonga<\/option><option value=\"Trinidad and Tobago\" data-country-code=\"TT\" >Trinidad and Tobago<\/option><option value=\"Tunisia\" data-country-code=\"TN\" >Tunisia<\/option><option value=\"Turkey\" data-country-code=\"TR\" >Turkey<\/option><option value=\"Turkmenistan\" data-country-code=\"TM\" >Turkmenistan<\/option><option value=\"Turks And Caicos Islands\" data-country-code=\"TC\" >Turks And Caicos Islands<\/option><option value=\"Tuvalu\" data-country-code=\"TV\" >Tuvalu<\/option><option value=\"Uganda\" data-country-code=\"UG\" >Uganda<\/option><option value=\"Ukraine\" data-country-code=\"UA\" >Ukraine<\/option><option value=\"United Arab Emirates\" data-country-code=\"AE\" >United Arab Emirates<\/option><option value=\"United Kingdom\" data-country-code=\"GB\" >United Kingdom<\/option><option value=\"US Minor Outlying Islands\" data-country-code=\"UM\" >US Minor Outlying Islands<\/option><option value=\"United States of America (USA)\" data-country-code=\"US\" >United States of America (USA)<\/option><option value=\"Uruguay\" data-country-code=\"UY\" >Uruguay<\/option><option value=\"Uzbekistan\" data-country-code=\"UZ\" >Uzbekistan<\/option><option value=\"Vanuatu\" data-country-code=\"VU\" >Vanuatu<\/option><option value=\"Vatican City\" data-country-code=\"VA\" >Vatican City<\/option><option value=\"Venezuela\" data-country-code=\"VE\" >Venezuela<\/option><option value=\"Vietnam\" data-country-code=\"VN\" >Vietnam<\/option><option value=\"Virgin Islands, British\" data-country-code=\"VG\" >Virgin Islands, British<\/option><option value=\"Virgin Islands, U.S.\" data-country-code=\"VI\" >Virgin Islands, U.S.<\/option><option value=\"Wallis And Futuna Islands\" data-country-code=\"WF\" >Wallis And Futuna Islands<\/option><option value=\"Western Sahara\" data-country-code=\"EH\" >Western Sahara<\/option><option value=\"Yemen Arab Rep.\" data-country-code=\"YE\" >Yemen Arab Rep.<\/option><option value=\"Yemen Democratic\" data-country-code=\"YD\" >Yemen Democratic<\/option><option value=\"Zambia\" data-country-code=\"ZM\" >Zambia<\/option><option value=\"Zimbabwe\" data-country-code=\"ZW\" >Zimbabwe<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"text-1\" class=\"forminator-field-text forminator-col forminator-col-6 \"><div class=\"forminator-field\"><label for=\"forminator-field-text-1_6a57ec0f61893\" id=\"forminator-field-text-1_6a57ec0f61893-label\" class=\"forminator-label\">Company <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"text-1\" value=\"\" placeholder=\"\" id=\"forminator-field-text-1_6a57ec0f61893\" class=\"forminator-input forminator-name--field\" data-required=\"1\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"radio-1\" class=\"forminator-field-radio forminator-col forminator-col-12 \"><div role=\"radiogroup\" class=\"forminator-field\" aria-labelledby=\"forminator-radiogroup-6a57ec0f61893-label\" aria-describedby=\"forminator-radiogroup-6a57ec0f61893-description\"><label id=\"forminator-field-radio-1-label-1\" for=\"forminator-field-radio-1-1-6a57ec0f61893\" class=\"forminator-radio\" title=\"i agree\"><input type=\"radio\" name=\"radio-1\" value=\"one\" id=\"forminator-field-radio-1-1-6a57ec0f61893\" aria-labelledby=\"forminator-field-radio-1-label-1\" data-calculation=\"0\"   data-hidden-behavior=\"zero\" aria-describedby=\"forminator-field-radio-1-6a57ec0f61893-description\"\/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">i agree<\/span><\/label><label id=\"forminator-field-radio-1-label-2\" for=\"forminator-field-radio-1-2-6a57ec0f61893\" class=\"forminator-radio\" title=\"i don&#039;t agree\"><input type=\"radio\" name=\"radio-1\" value=\"two\" id=\"forminator-field-radio-1-2-6a57ec0f61893\" aria-labelledby=\"forminator-field-radio-1-label-2\" data-calculation=\"0\"   data-hidden-behavior=\"zero\" aria-describedby=\"forminator-field-radio-1-6a57ec0f61893-description\"\/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">i don't agree<\/span><\/label><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"html-2\" class=\"forminator-field-html forminator-col forminator-col-12 \"><div class=\"forminator-field forminator-merge-tags\" data-field=\"html-2\"><label class=\"forminator-label\">HTML<\/label><p>to the processing of data for the purposes of direct marketing, for sending commercial and promotional communications through automated methods of contact (eg e-mail,) referred to in point (1.3) of the <\/p> <a href=\"\/global\/en\/privacy-policy-spk\" target=\"_blank\">privacy notice *<\/a><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"captcha-1\" class=\"forminator-field-captcha forminator-col forminator-col-12 \"><div class=\"forminator-g-recaptcha\" data-theme=\"light\"  data-sitekey=\"6Lc5IL4pAAAAANOn8KTTdmazMhjf54FY0u4nXnGP\" data-size=\"normal\"><\/div> <\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">Send Message<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"d02adc0b94\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/global\/en\/wp-json\/wp\/v2\/pages\/7606\" \/><input type=\"hidden\" name=\"form_id\" value=\"6039\"><input type=\"hidden\" name=\"page_id\" value=\"7606\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/www.came.com\/global\/en\/spk-landing\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><\/form><\/div>\n\n\n\n<style>\n  .s9 {background-image: none;}\n  \/**\n  .form-contacts {position: absolute;top: 0;z-index: -1; opacity: 0; transition: all 0.5s step-end;}\n  .fp-viewing-s9 .form-contacts {z-index: 1; opacity: 1;}**\/\n<\/style>\n  <script src=\"https:\/\/code.jquery.com\/jquery-3.7.1.min.js\" integrity=\"sha256-\/JqT3SQfawRcv\/BIHPThkBvs0OEvtFFmqPF\/lYI\/Cxo=\" crossorigin=\"anonymous\"><\/script>\n<script>\n    window.addEventListener('DOMContentLoaded', function() {\n        (function($) {\n            $('.-fixed-width').appendTo( $('#section-footer-form') );\n        })(jQuery);\n    });\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>ZERO KM SERVICE A BREAKTHROUGH IN PARKING SERVICE WATCH THE VIDEO&nbsp;&gt; CONTACT US FOR MORE INFO&nbsp;&gt; SCROLL DOWN TO DISCOVER MORE X A CUTTING EDGE CONCEPT TO CHANGE PARKING SERVICE FOREVER no need to call the Service provider no more waiting for a specialised technician no stress for the car park manager Discover our innovative [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_template-landing-fullscreen.php","meta":{"elastic_search":"","powered_cache_disable_cache":false,"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/pages\/7606"}],"collection":[{"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/comments?post=7606"}],"version-history":[{"count":3,"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/pages\/7606\/revisions"}],"predecessor-version":[{"id":7609,"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/pages\/7606\/revisions\/7609"}],"wp:attachment":[{"href":"https:\/\/www.came.com\/global\/en\/wp-json\/wp\/v2\/media?parent=7606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}